{"id":8507,"date":"2022-09-19T14:04:15","date_gmt":"2022-09-19T12:04:15","guid":{"rendered":"https:\/\/supdeco.sn\/?p=8507"},"modified":"2022-09-19T14:05:45","modified_gmt":"2022-09-19T12:05:45","slug":"exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts","status":"publish","type":"post","link":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/","title":{"rendered":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/supdeco.sn\/fr\/wp-json\/wp\/v2\/posts\/8507\" class=\"qtranxs-available-language-link qtranxs-available-language-link-fr\" title=\"Fran\u00e7ais\">Fran\u00e7ais<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Fran\u00e7ais.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8507","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sorry, this entry is only available in Fran\u00e7ais.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Babacar Lo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Supdeco Dakar - Business School\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts - Supdeco Dakar\" \/>\n\t\t<meta property=\"og:description\" content=\"Sorry, this entry is only available in Fran\u00e7ais.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1167\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-09-19T12:04:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-19T12:05:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeSupdecoDakar\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@SupdeCoDakar\" \/>\n\t\t<meta name=\"twitter:title\" content=\"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts - Supdeco Dakar\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sorry, this entry is only available in Fran\u00e7ais.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@SupdeCoDakar\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#blogposting\",\"name\":\"(Fran\\u00e7ais) Exploitation du p\\u00e9trole du Gaz au S\\u00e9n\\u00e9gal : Le Groupe Supdeco donne la parole aux experts - Supdeco Dakar\",\"headline\":\"(Fran\\u00e7ais) Exploitation du p\\u00e9trole du Gaz au S\\u00e9n\\u00e9gal : Le Groupe Supdeco donne la parole aux experts\",\"author\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/author\\\/lo-babacar2supdeco-edu-sn\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo8supdeco-1.png\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#articleImage\",\"width\":338,\"height\":355},\"datePublished\":\"2022-09-19T14:04:15+02:00\",\"dateModified\":\"2022-09-19T14:05:45+02:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#webpage\"},\"articleSection\":\"Non class\\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/supdeco.sn\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/category\\\/non-classe\\\/#listItem\",\"name\":\"Non class\\u00e9\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/category\\\/non-classe\\\/#listItem\",\"position\":2,\"name\":\"Non class\\u00e9\",\"item\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/category\\\/non-classe\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#listItem\",\"name\":\"(Fran\\u00e7ais) Exploitation du p\\u00e9trole du Gaz au S\\u00e9n\\u00e9gal : Le Groupe Supdeco donne la parole aux experts\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#listItem\",\"position\":3,\"name\":\"(Fran\\u00e7ais) Exploitation du p\\u00e9trole du Gaz au S\\u00e9n\\u00e9gal : Le Groupe Supdeco donne la parole aux experts\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/category\\\/non-classe\\\/#listItem\",\"name\":\"Non class\\u00e9\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#organization\",\"name\":\"Supdeco\",\"description\":\"Business School\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo8supdeco-1.png\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#organizationLogo\",\"width\":338,\"height\":355},\"image\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GroupeSupdecoDakar\",\"https:\\\/\\\/twitter.com\\\/SupdeCoDakar\",\"https:\\\/\\\/www.instagram.com\\\/supdecodakar\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/SupdeCoDakar\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/groupesupdecodakar\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/author\\\/lo-babacar2supdeco-edu-sn\\\/#author\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/author\\\/lo-babacar2supdeco-edu-sn\\\/\",\"name\":\"Babacar Lo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c4cc828b2ab3b69ca2a3a545b046bd1915345e897c7f434c1e7d5a6d7db565fe?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Babacar Lo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#webpage\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/\",\"name\":\"(Fran\\u00e7ais) Exploitation du p\\u00e9trole du Gaz au S\\u00e9n\\u00e9gal : Le Groupe Supdeco donne la parole aux experts - Supdeco Dakar\",\"description\":\"Sorry, this entry is only available in Fran\\u00e7ais.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/author\\\/lo-babacar2supdeco-edu-sn\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/author\\\/lo-babacar2supdeco-edu-sn\\\/#author\"},\"datePublished\":\"2022-09-19T14:04:15+02:00\",\"dateModified\":\"2022-09-19T14:05:45+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/\",\"name\":\"Supdeco Dakar\",\"description\":\"Business School\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts - Supdeco Dakar","description":"Sorry, this entry is only available in Fran\u00e7ais.","canonical_url":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#blogposting","name":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts - Supdeco Dakar","headline":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts","author":{"@id":"https:\/\/supdeco.sn\/en\/author\/lo-babacar2supdeco-edu-sn\/#author"},"publisher":{"@id":"https:\/\/supdeco.sn\/en\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/logo8supdeco-1.png","@id":"https:\/\/supdeco.sn\/en\/#articleImage","width":338,"height":355},"datePublished":"2022-09-19T14:04:15+02:00","dateModified":"2022-09-19T14:05:45+02:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#webpage"},"isPartOf":{"@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#webpage"},"articleSection":"Non class\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en#listItem","position":1,"name":"Accueil","item":"https:\/\/supdeco.sn\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en\/category\/non-classe\/#listItem","name":"Non class\u00e9"}},{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en\/category\/non-classe\/#listItem","position":2,"name":"Non class\u00e9","item":"https:\/\/supdeco.sn\/en\/category\/non-classe\/","nextItem":{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#listItem","name":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts"},"previousItem":{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#listItem","position":3,"name":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts","previousItem":{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en\/category\/non-classe\/#listItem","name":"Non class\u00e9"}}]},{"@type":"Organization","@id":"https:\/\/supdeco.sn\/en\/#organization","name":"Supdeco","description":"Business School","url":"https:\/\/supdeco.sn\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/logo8supdeco-1.png","@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#organizationLogo","width":338,"height":355},"image":{"@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/GroupeSupdecoDakar","https:\/\/twitter.com\/SupdeCoDakar","https:\/\/www.instagram.com\/supdecodakar\/","https:\/\/www.youtube.com\/user\/SupdeCoDakar","https:\/\/www.linkedin.com\/school\/groupesupdecodakar"]},{"@type":"Person","@id":"https:\/\/supdeco.sn\/en\/author\/lo-babacar2supdeco-edu-sn\/#author","url":"https:\/\/supdeco.sn\/en\/author\/lo-babacar2supdeco-edu-sn\/","name":"Babacar Lo","image":{"@type":"ImageObject","@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c4cc828b2ab3b69ca2a3a545b046bd1915345e897c7f434c1e7d5a6d7db565fe?s=96&d=mm&r=g","width":96,"height":96,"caption":"Babacar Lo"}},{"@type":"WebPage","@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#webpage","url":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/","name":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts - Supdeco Dakar","description":"Sorry, this entry is only available in Fran\u00e7ais.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/supdeco.sn\/en\/#website"},"breadcrumb":{"@id":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/#breadcrumblist"},"author":{"@id":"https:\/\/supdeco.sn\/en\/author\/lo-babacar2supdeco-edu-sn\/#author"},"creator":{"@id":"https:\/\/supdeco.sn\/en\/author\/lo-babacar2supdeco-edu-sn\/#author"},"datePublished":"2022-09-19T14:04:15+02:00","dateModified":"2022-09-19T14:05:45+02:00"},{"@type":"WebSite","@id":"https:\/\/supdeco.sn\/en\/#website","url":"https:\/\/supdeco.sn\/en\/","name":"Supdeco Dakar","description":"Business School","inLanguage":"en-US","publisher":{"@id":"https:\/\/supdeco.sn\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Supdeco Dakar - Business School","og:type":"article","og:title":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts - Supdeco Dakar","og:description":"Sorry, this entry is only available in Fran\u00e7ais.","og:url":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/","og:image":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg","og:image:secure_url":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg","og:image:width":1400,"og:image:height":1167,"article:published_time":"2022-09-19T12:04:15+00:00","article:modified_time":"2022-09-19T12:05:45+00:00","article:publisher":"https:\/\/www.facebook.com\/GroupeSupdecoDakar","twitter:card":"summary_large_image","twitter:site":"@SupdeCoDakar","twitter:title":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts - Supdeco Dakar","twitter:description":"Sorry, this entry is only available in Fran\u00e7ais.","twitter:creator":"@SupdeCoDakar","twitter:image":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg"},"aioseo_meta_data":{"post_id":"8507","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-10-03 18:26:08","updated":"2026-06-11 10:54:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/supdeco.sn\/en\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/supdeco.sn\/en\/category\/non-classe\/\" title=\"Non class\u00e9\">Non class\u00e9<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/supdeco.sn\/en"},{"label":"Non class\u00e9","link":"https:\/\/supdeco.sn\/en\/category\/non-classe\/"},{"label":"(Fran\u00e7ais) Exploitation du p\u00e9trole du Gaz au S\u00e9n\u00e9gal : Le Groupe Supdeco donne la parole aux experts","link":"https:\/\/supdeco.sn\/en\/exploitation-du-petrole-du-gaz-au-senegal-le-groupe-supdeco-donne-la-parole-aux-experts\/"}],"_links":{"self":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/posts\/8507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/comments?post=8507"}],"version-history":[{"count":2,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/posts\/8507\/revisions"}],"predecessor-version":[{"id":8509,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/posts\/8507\/revisions\/8509"}],"wp:attachment":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/media?parent=8507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/categories?post=8507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/tags?post=8507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}