{"id":6742,"date":"2021-11-11T12:18:25","date_gmt":"2021-11-11T11:18:25","guid":{"rendered":"http:\/\/supdeco.chezak.net\/?page_id=6742"},"modified":"2022-09-07T14:22:01","modified_gmt":"2022-09-07T12:22:01","slug":"nos-professeurs-et-chercheurs","status":"publish","type":"page","link":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/","title":{"rendered":"Our Teachers and Researchers"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-6742","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Supdeco Dakar - Business School\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Our Teachers and Researchers - Supdeco Dakar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1167\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-11-11T11:18:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-07T12:22:01+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeSupdecoDakar\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@SupdeCoDakar\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Our Teachers and Researchers - Supdeco Dakar\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@SupdeCoDakar\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/nos-professeurs-et-chercheurs\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/supdeco.sn\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/nos-professeurs-et-chercheurs\\\/#listItem\",\"name\":\"Our Teachers and Researchers\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/nos-professeurs-et-chercheurs\\\/#listItem\",\"position\":2,\"name\":\"Our Teachers and Researchers\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en#listItem\",\"name\":\"Accueil\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#organization\",\"name\":\"Supdeco\",\"description\":\"Business School\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo8supdeco-1.png\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/nos-professeurs-et-chercheurs\\\/#organizationLogo\",\"width\":338,\"height\":355},\"image\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/nos-professeurs-et-chercheurs\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GroupeSupdecoDakar\",\"https:\\\/\\\/twitter.com\\\/SupdeCoDakar\",\"https:\\\/\\\/www.instagram.com\\\/supdecodakar\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/SupdeCoDakar\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/groupesupdecodakar\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/nos-professeurs-et-chercheurs\\\/#webpage\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/nos-professeurs-et-chercheurs\\\/\",\"name\":\"Our Teachers and Researchers - Supdeco Dakar\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/nos-professeurs-et-chercheurs\\\/#breadcrumblist\"},\"datePublished\":\"2021-11-11T12:18:25+01:00\",\"dateModified\":\"2022-09-07T14:22:01+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/\",\"name\":\"Supdeco Dakar\",\"description\":\"Business School\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Our Teachers and Researchers - Supdeco Dakar","description":"","canonical_url":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en#listItem","position":1,"name":"Accueil","item":"https:\/\/supdeco.sn\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/#listItem","name":"Our Teachers and Researchers"}},{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/#listItem","position":2,"name":"Our Teachers and Researchers","previousItem":{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en#listItem","name":"Accueil"}}]},{"@type":"Organization","@id":"https:\/\/supdeco.sn\/en\/#organization","name":"Supdeco","description":"Business School","url":"https:\/\/supdeco.sn\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/logo8supdeco-1.png","@id":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/#organizationLogo","width":338,"height":355},"image":{"@id":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/GroupeSupdecoDakar","https:\/\/twitter.com\/SupdeCoDakar","https:\/\/www.instagram.com\/supdecodakar\/","https:\/\/www.youtube.com\/user\/SupdeCoDakar","https:\/\/www.linkedin.com\/school\/groupesupdecodakar"]},{"@type":"WebPage","@id":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/#webpage","url":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/","name":"Our Teachers and Researchers - Supdeco Dakar","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/supdeco.sn\/en\/#website"},"breadcrumb":{"@id":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/#breadcrumblist"},"datePublished":"2021-11-11T12:18:25+01:00","dateModified":"2022-09-07T14:22:01+02:00"},{"@type":"WebSite","@id":"https:\/\/supdeco.sn\/en\/#website","url":"https:\/\/supdeco.sn\/en\/","name":"Supdeco Dakar","description":"Business School","inLanguage":"en-US","publisher":{"@id":"https:\/\/supdeco.sn\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Supdeco Dakar - Business School","og:type":"article","og:title":"Our Teachers and Researchers - Supdeco Dakar","og:url":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/","og:image":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg","og:image:secure_url":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg","og:image:width":1400,"og:image:height":1167,"article:published_time":"2021-11-11T11:18:25+00:00","article:modified_time":"2022-09-07T12:22:01+00:00","article:publisher":"https:\/\/www.facebook.com\/GroupeSupdecoDakar","twitter:card":"summary_large_image","twitter:site":"@SupdeCoDakar","twitter:title":"Our Teachers and Researchers - Supdeco Dakar","twitter:creator":"@SupdeCoDakar","twitter:image":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg"},"aioseo_meta_data":{"post_id":"6742","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-10-03 18:19:01","updated":"2026-06-11 10:44:31","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/supdeco.sn\/en\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOur Teachers and Researchers\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/supdeco.sn\/en"},{"label":"Our Teachers and Researchers","link":"https:\/\/supdeco.sn\/en\/nos-professeurs-et-chercheurs\/"}],"_links":{"self":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/pages\/6742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/comments?post=6742"}],"version-history":[{"count":5,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/pages\/6742\/revisions"}],"predecessor-version":[{"id":8445,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/pages\/6742\/revisions\/8445"}],"wp:attachment":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/media?parent=6742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}