{"id":6763,"date":"2021-11-11T17:07:19","date_gmt":"2021-11-11T16:07:19","guid":{"rendered":"http:\/\/supdeco.chezak.net\/?post_type=equipe&#038;p=6763"},"modified":"2022-09-05T12:08:51","modified_gmt":"2022-09-05T10:08:51","slug":"falou-ndoye","status":"publish","type":"equipe","link":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/","title":{"rendered":"Aito de la Rua"},"content":{"rendered":"","protected":false},"featured_media":8328,"template":"","class_list":["post-6763","equipe","type-equipe","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Supdeco Dakar - Business School\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Aito de la Rua - Supdeco Dakar\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1167\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-11-11T16:07:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-05T10:08:51+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeSupdecoDakar\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@SupdeCoDakar\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Aito de la Rua - Supdeco Dakar\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/supdeco.sn\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/#listItem\",\"name\":\"Aito de la Rua\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/#listItem\",\"position\":2,\"name\":\"Aito de la Rua\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en#listItem\",\"name\":\"Accueil\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#organization\",\"name\":\"Supdeco\",\"description\":\"Business School\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/logo8supdeco-1.png\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/#organizationLogo\",\"width\":338,\"height\":355},\"image\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GroupeSupdecoDakar\",\"https:\\\/\\\/twitter.com\\\/SupdeCoDakar\",\"https:\\\/\\\/www.instagram.com\\\/supdecodakar\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/SupdeCoDakar\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/groupesupdecodakar\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/#webpage\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/\",\"name\":\"Aito de la Rua - Supdeco Dakar\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/F.jpeg\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/#mainImage\",\"width\":286,\"height\":300},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/equipe\\\/falou-ndoye\\\/#mainImage\"},\"datePublished\":\"2021-11-11T17:07:19+01:00\",\"dateModified\":\"2022-09-05T12:08:51+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/\",\"name\":\"Supdeco Dakar\",\"description\":\"Business School\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/supdeco.sn\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Aito de la Rua - Supdeco Dakar","description":"","canonical_url":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en#listItem","position":1,"name":"Accueil","item":"https:\/\/supdeco.sn\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/#listItem","name":"Aito de la Rua"}},{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/#listItem","position":2,"name":"Aito de la Rua","previousItem":{"@type":"ListItem","@id":"https:\/\/supdeco.sn\/en#listItem","name":"Accueil"}}]},{"@type":"Organization","@id":"https:\/\/supdeco.sn\/en\/#organization","name":"Supdeco","description":"Business School","url":"https:\/\/supdeco.sn\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/logo8supdeco-1.png","@id":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/#organizationLogo","width":338,"height":355},"image":{"@id":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/GroupeSupdecoDakar","https:\/\/twitter.com\/SupdeCoDakar","https:\/\/www.instagram.com\/supdecodakar\/","https:\/\/www.youtube.com\/user\/SupdeCoDakar","https:\/\/www.linkedin.com\/school\/groupesupdecodakar"]},{"@type":"WebPage","@id":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/#webpage","url":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/","name":"Aito de la Rua - Supdeco Dakar","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/supdeco.sn\/en\/#website"},"breadcrumb":{"@id":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/F.jpeg","@id":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/#mainImage","width":286,"height":300},"primaryImageOfPage":{"@id":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/#mainImage"},"datePublished":"2021-11-11T17:07:19+01:00","dateModified":"2022-09-05T12:08:51+02:00"},{"@type":"WebSite","@id":"https:\/\/supdeco.sn\/en\/#website","url":"https:\/\/supdeco.sn\/en\/","name":"Supdeco Dakar","description":"Business School","inLanguage":"en-US","publisher":{"@id":"https:\/\/supdeco.sn\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Supdeco Dakar - Business School","og:type":"article","og:title":"Aito de la Rua - Supdeco Dakar","og:url":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/","og:image":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg","og:image:secure_url":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg","og:image:width":1400,"og:image:height":1167,"article:published_time":"2021-11-11T16:07:19+00:00","article:modified_time":"2022-09-05T10:08:51+00:00","article:publisher":"https:\/\/www.facebook.com\/GroupeSupdecoDakar","twitter:card":"summary_large_image","twitter:site":"@SupdeCoDakar","twitter:title":"Aito de la Rua - Supdeco Dakar","twitter:image":"https:\/\/supdeco.sn\/wp-content\/uploads\/2021\/11\/Bourse-dExellence_336x280-1.jpeg"},"aioseo_meta_data":{"post_id":"6763","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-10-03 18:06:15","updated":"2026-06-11 10:28:17","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/supdeco.sn\/en\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAito de la Rua\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/supdeco.sn\/en"},{"label":"Aito de la Rua","link":"https:\/\/supdeco.sn\/en\/equipe\/falou-ndoye\/"}],"_links":{"self":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/equipe\/6763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/equipe"}],"about":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/types\/equipe"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/media\/8328"}],"wp:attachment":[{"href":"https:\/\/supdeco.sn\/en\/wp-json\/wp\/v2\/media?parent=6763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}